{"id":6434,"date":"2017-06-26T21:52:20","date_gmt":"2017-06-27T00:52:20","guid":{"rendered":"http:\/\/nautic.wnpower.host\/?p=6434"},"modified":"2017-06-26T21:52:20","modified_gmt":"2017-06-27T00:52:20","slug":"corredor-turistico-fluvial-del-litoral-de-argentina","status":"publish","type":"post","link":"https:\/\/nautica.news\/es\/corredor-turistico-fluvial-del-litoral-de-argentina\/","title":{"rendered":"Corredor Tur\u00edstico Fluvial del Litoral de Argentina"},"content":{"rendered":"<p><strong><em>Se \u00a0firm\u00f3 un acta para el desarrollo del Corredor Tur\u00edstico Fluvial del Litoral de Argentina. El plan contempla fortalecer el producto tur\u00edstico de cruceros con servicio a bordo en la hidrov\u00eda Paran\u00e1-Paraguay, en una primera etapa.<\/em><\/strong><\/p>\n<p>La Argentina est\u00e1 comenzando a avizorar hacia sus aguas. Mares, lagos, arroyos y r\u00edos conforman su extensa geograf\u00eda, ideal para el desarrollo de diversas actividades n\u00e1uticas, tanto deportivas como tur\u00edsticas.<\/p>\n<div id=\"attachment_8041\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8041\" src=\"http:\/\/www.revistamundonautico.com\/uploads\/Impulsan2.jpg\" alt=\"\" width=\"450\" height=\"338\" data-id=\"8041\" title=\"\"><\/p>\n<p class=\"wp-caption-text\">\n<\/div>\n<p>Desde no hace mucho tiempo se est\u00e1 empezando a trabajar en planes para el desarrollo del turismo n\u00e1utico y recientemente se dio impulso a un plan que abarca el desarrollo del Corredor Tur\u00edstico Fluvial del Litoral de Argentina.<\/p>\n<p>Se trata de un proyecto que tiene por objeto fortalecer el producto tur\u00edstico de cruceros con servicio a bordo en la hidrov\u00eda Paran\u00e1-Paraguay. Es as\u00ed que se firm\u00f3 un acuerdo que involucra al Ministerio de Turismo de la Naci\u00f3n, el Consejo Federal de Inversiones, y los gobiernos de Corrientes, Entre R\u00edos, Misiones y Santa Fe.<\/p>\n<div id=\"attachment_8042\" class=\"wp-caption aligncenter\"><\/div>\n<p>\u201c<em>Es una propuesta que generar\u00e1 gran dinamismo econ\u00f3mico en la regi\u00f3n, impactante, sustentable, y con un inmejorable perfil federal en cuanto a la generaci\u00f3n de empleos y distribuci\u00f3n del ingreso<\/em>\u201d, sostiene el ministro de Turismo de la Naci\u00f3n, Gustavo Santos.<\/p>\n<p><strong>El plan<\/strong><\/p>\n<p>El Plan de Turismo Fluvial est\u00e1 planteado para la hidrov\u00eda Paran\u00e1-Paraguay: son 2.365 kil\u00f3metros de extensi\u00f3n que se identificar\u00e1n en seis\u00a0 tramos e involucra a siete\u00a0provincias. Es una v\u00eda muy importante para el intercambio del comercio y zona de influencia del Mercosur, por lo que su navegabilidad ha estado abocada principalmente a este tipo de actividad. A esa cuenca, adem\u00e1s, se sumar\u00e1 el r\u00edo Bermejo que se encuentra en el norte del pa\u00eds (cuenca compartida con Bolivia).<\/p>\n<p>El plan est\u00e1 dise\u00f1ado en tres ejes: cruceros fluviales, catamaranes fluviales y desarrollo costero. Para estos dos \u00faltimos, las obras (rampas, pasarelas, grupos sanitarios) permitir\u00e1n, una vez concluidas, captar cerca de 80.000 embarcaciones vinculadas a los m\u00e1s de 350 clubes n\u00e1uticos inscritos a lo largo de toda la cuenca.<\/p>\n<div id=\"attachment_8043\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8043\" src=\"http:\/\/www.revistamundonautico.com\/uploads\/Impulsan1.jpg\" alt=\"\" width=\"374\" height=\"486\" data-id=\"8043\" title=\"\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se \u00a0firm\u00f3 un acta para el desarrollo del Corredor Tur\u00edstico Fluvial del Litoral de Argentina. El plan contempla fortalecer el producto tur\u00edstico de cruceros con servicio a bordo en la hidrov\u00eda Paran\u00e1-Paraguay, en una primera etapa. La Argentina est\u00e1 comenzando a avizorar hacia sus aguas. Mares, lagos, arroyos y r\u00edos conforman su extensa geograf\u00eda, ideal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6435,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[86],"tags":[],"class_list":["post-6434","post","type-post","status-publish","format-standard","has-post-thumbnail","category-interes"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/6434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/comments?post=6434"}],"version-history":[{"count":0,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/6434\/revisions"}],"wp:attachment":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/media?parent=6434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/categories?post=6434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/tags?post=6434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}