{"id":47659,"date":"2023-05-17T09:08:43","date_gmt":"2023-05-17T12:08:43","guid":{"rendered":"http:\/\/nautic.wnpower.host\/?p=47659"},"modified":"2023-05-17T09:08:43","modified_gmt":"2023-05-17T12:08:43","slug":"nautia-seguros-apuesta-por-la-clase-j70-en-espana","status":"publish","type":"post","link":"https:\/\/nautica.news\/es\/nautia-seguros-apuesta-por-la-clase-j70-en-espana\/","title":{"rendered":"Nautia Seguros apuesta por la clase J70 en Espa\u00f1a"},"content":{"rendered":"<p>La corredur\u00eda de seguros n\u00e1uticos Nautia y la clase J70 en Espa\u00f1a han firmado este mes de mayo un acuerdo de patrocinio para todo lo que queda de temporada 2023.<\/p>\n<p>El objetivo de la Asociaci\u00f3n de Propietarios de J70 en Espa\u00f1a es potenciar este divertido monotipo en toda la geograf\u00eda espa\u00f1ola.<\/p>\n<p>Esta asociaci\u00f3n es la responsable de la Copa de Espa\u00f1a, que este a\u00f1o celebra su primera edici\u00f3n en Barcelona, del 19 al 21 de mayo, en coorganizaci\u00f3n con el Real Club N\u00e1utico de Barcelona.<\/p>\n<p>La asociaci\u00f3n tambi\u00e9n organiza el Campeonato de Espa\u00f1a que tendr\u00e1 lugar en la isla de La Toja (Vigo), del 16 al 18 de junio.<\/p>\n<p>Con m\u00e1s de 20 a\u00f1os de experiencia, Nautia tiene como misi\u00f3n estar al lado de los navegantes y regatistas, por ello apuesta por esta colaboraci\u00f3n estrat\u00e9gica con la clase monotipo m\u00e1s de moda actualmente en Espa\u00f1a y tambi\u00e9n por su enorme proyecci\u00f3n.<\/p>\n<p>El patrocinio de la corredur\u00eda especializada se materializa con un seguro completo de cortes\u00eda para tres armadores. Los agraciados se conocer\u00e1n despu\u00e9s de los eventos de Barcelona y Vigo, mientras que el tercero saldr\u00e1 de la clasificaci\u00f3n del ranking nacional y se entregar\u00e1 durante la Copa del Rey Mapfre, en Palma de Mallorca, este verano.<br \/>\nRanking nacional de J70<br \/>\nLa Copa y el Campeonato de Espa\u00f1a servir\u00e1n para conocer el ranking nacional, con el que se conocer\u00e1 el nombre de los equipos que podr\u00e1n representar a Espa\u00f1a en el pr\u00f3ximo campeonato del Mundo, que se celebrar\u00e1 en Palma de Mallorca en septiembre de 2024.<br \/>\nA pesar de que intervengan los dos eventos para la clasificaci\u00f3n del ranking, cada competici\u00f3n cuenta con una ponderaci\u00f3n diferente, siendo mayor el Campeonato de Espa\u00f1a (60%) que la Copa de Espa\u00f1a (40%).<br \/>\nM\u00e1s de 25 equipos procedentes de Palma de Mallorca, Galicia, Barcelona, L\u2019Escala o D\u00e8nia participar\u00e1n en estos eventos, que tambi\u00e9n contar\u00e1n con equipos de pa\u00edses europeos como Portugal, Alemania, Inglaterra, Italia e incluso ya se ha confirmado la participaci\u00f3n de un equipo australiano, lo que representa todo un \u00e9xito para la clase J70 y para Nautia.<br \/>\nNautia Seguros<br \/>\nNautia es una corredur\u00eda de seguros, que tambi\u00e9n ofrece servicios de consultor\u00eda y gestor\u00eda n\u00e1utica.<br \/>\nA trav\u00e9s del sitio web nautia.net se puede calcular de manera muy f\u00e1cil y r\u00e1pida el seguro a terceros para barcos con un comparador de seguros. Nautia ofrece un asesoramiento personalizado para quienes desean una cobertura m\u00e1s completa en el seguro de su embarcaci\u00f3n de recreo. Al ser gestores administrativos colegiados, pueden ayudar como gestor\u00eda n\u00e1utica especializada asesorando en la compra y tramitaci\u00f3n de la documentaci\u00f3n del barco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La corredur\u00eda de seguros n\u00e1uticos Nautia y la clase J70 en Espa\u00f1a han firmado este mes de mayo un acuerdo de patrocinio para todo lo que queda de temporada 2023. El objetivo de la Asociaci\u00f3n de Propietarios de J70 en Espa\u00f1a es potenciar este divertido monotipo en toda la geograf\u00eda espa\u00f1ola. Esta asociaci\u00f3n es la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":47660,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[83],"tags":[203,3376],"class_list":["post-47659","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-nautica","tag-j70","tag-nautia-seguros"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/47659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/comments?post=47659"}],"version-history":[{"count":0,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/47659\/revisions"}],"wp:attachment":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/media?parent=47659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/categories?post=47659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/tags?post=47659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}