{"id":47521,"date":"2023-05-03T08:00:08","date_gmt":"2023-05-03T11:00:08","guid":{"rendered":"http:\/\/nautic.wnpower.host\/?p=47521"},"modified":"2023-05-03T08:00:08","modified_gmt":"2023-05-03T11:00:08","slug":"tres-regatas-frente-a-las-ciesresuelven-un-trofeo-repsol-muy-igualado","status":"publish","type":"post","link":"https:\/\/nautica.news\/es\/tres-regatas-frente-a-las-ciesresuelven-un-trofeo-repsol-muy-igualado\/","title":{"rendered":"Tres regatas frente a las C\u00edesresuelven un Trofeo Repsol muy igualado"},"content":{"rendered":"<h3>Trofeo Repsol<\/h3>\n<p>El Parque Nacional de las Islas Atl\u00e1nticas de Galicia fue espectador de lujo este primero de mayo de la \u00faltima y decisiva jornada del Trofeo Repsol \u2022 45\u00ba Regata de Primavera, que vivi\u00f3 este lunes sus tres \u00faltimas pruebasen el fondeadero de las islas C\u00edes.<br \/>\nAl igual que hab\u00eda sucedido en las dos etapas previas, Eolo se hizo de rogar y la flota tuvo que esperar esta vez m\u00e1s de hora y media que el viento hiciese acto de presencia. Tard\u00f3 en aparecer, pero una vez se present\u00f3, despleg\u00f3 muy buenas condiciones. Se disputaron las pruebas previstas en programa, tres recorridos en forma de trapecio (dos para los J80 y uno para los ORCs) que ser\u00edan decisivos de cara a conformar los podios de las diferentes clases.<br \/>\nLos campeones de esta cuadrag\u00e9simo quinta edici\u00f3n fueron el Sailway (CM Canido) en ORC 1-2-3, el Deep Blue 2.1 (RCN Vigo) en ORC 4, el Cinco Islas Albari\u00f1o (CN Beluso) en ORC 5, el Sala\u00f1o Dos (RCN Vigo) en A Dos, el Okofen de Javier de la G\u00e1ndara (MRCYB) en J80 y el Tutatis (MRCYB) en F\u00edgaro. Este \u00faltimo tambi\u00e9n se llev\u00f3 el premio especial a la mejor tripulaci\u00f3n femenina.<br \/>\nEn la clase ORC 1-2-3, con unos parciales de 2-2-2, el Sailway de Ram\u00f3n Ojea (CM Canido), con Alejandro P\u00e9rez a la ca\u00f1a, logr\u00f3 llevarse el oro de la competici\u00f3n. Su regularidad en los tres d\u00edas de competici\u00f3n le permiti\u00f3 adelantar a sus rivales y subirse a lo m\u00e1s alto del podio. El Bon III (CN Punta Lagoa) compens\u00f3 su descalificaci\u00f3n del domingo porfuera de l\u00ednea con un primer puesto este lunes. Una nueva victoria parcial que, sumada a la del s\u00e1bado, le otorg\u00f3 la plata del trofeo. Acab\u00f3 con 10 puntos empatado con el Narval de Jos\u00e9 Antonio Portas (CN Vilagarc\u00eda), que qued\u00f3 tercero.<br \/>\nEn la clase ORC 4, el Deep Blue 2.1 de Vicente Cid (RCN Vigo) no dio ni tregua ni opci\u00f3n a sus rivales. Fue el mejor, sin duda alguna. Hizo pleno de victorias y se alz\u00f3, con 3 puntos, con un m\u00e1s que merecido primer premio.El resto de cajones del podio los ocuparon, con 7 y 8 puntos, el Unus de Luis Garc\u00eda Trigo (MRCYB) La Burla Negra de Juan Jos\u00e9 Mart\u00ednez (CN Castrelo de Mi\u00f1o), segundo y tercero respectivamente.<\/p>\n<p>De regreso en tierra el patr\u00f3n y l\u00edder del Deep Blue 2.1, Vicente Cid, se mostraba entusiasmado por el \u00e9xito logrado en la regata y por el buen trabajo de su tripulaci\u00f3n. \u201cEl alma del Deep Blue 2.1 es su equipo y sin ellos no habr\u00eda sido posible -dijo-esta victoria. Llevamos muchos a\u00f1os navegando juntos, la compenetraci\u00f3n es total y nuestro objetivo es seguir sumando triunfos. El a\u00f1o pasado nos llevamos el Conde, el R\u00edas y el Pr\u00edncipe, y en este 2023 no queremos lograr menos\u201d.<br \/>\nEn la clase ORC 5, donde las dos primeras pruebas hab\u00edan dejado unos resultados muy ajustados en la parte alta de la tabla, la regata se resolvi\u00f3 tambi\u00e9n de una forma muy apretada. Acab\u00f3 con la victoria final del Cinco Islas Albari\u00f1o, de I\u00f1aki Carbajo (CN Beluso), empatado a 8 puntos con el segundo clasificado, el Nahela de V\u00edctor Manuel \u00c1lvarez (CD Alagua), y a apenas medio punto de separaci\u00f3n con el tercero, el Squid II de Francisco Lusqui\u00f1os (CN Portonovo).<br \/>\nEn la clase A2, el Sala\u00f1o Dos de Jacobo Vecino y Brenda Maure (RCN Vigo), fue el \u00fanico barco junto con el Deep Blue que se impuso en todas y cada una de las regatas disputadas. Acab\u00f3 con tres oros parciales y con los laureles del trofeo primaveral. La plata fue para el Aquil\u00f3n de Roberto Telle y Genoveva Pereiro (MRCYB) y el bronce para el Asante Sana de Juan Carlos Trabazos y Joaqu\u00edn Dasilva (LM Bouzas).<br \/>\nLa clase J80 lleg\u00f3 a la jornada final liderada por el Okofen de Javier de la G\u00e1ndara, empatado a puntos con el Alboroto de Javier Aguado. En el programa del d\u00eda, al igual que los ORCs, dos pruebas de formato trapecio en las que ninguno pod\u00eda fallar si quer\u00eda llevarse los laureles. Finalmente, un primero y un segundo en las mangas inclinaron la balanza a favor del Okofen permiti\u00e9ndole subirse a lo m\u00e1s alto del podio. El Alboroto se vio lastrado a la tercera posici\u00f3n por un noveno puesto que firm\u00f3 en una de las pruebas y el Mar\u00edas de Manel Cunha le pas\u00f3 por delante, haci\u00e9ndose con la plata.<br \/>\nAunque compitieron dentro de la clase de los ORC-4, los F\u00edgaros del Monte Real tambi\u00e9n tuvieron categor\u00eda propia en la entrega de premios de esta cuadrag\u00e9simo quinta edici\u00f3n de la Regata de Primavera. Los vencedores de esta edici\u00f3n fueron el Tutatis de Paula Rey, el Ladeira de Elena Raga y el Erizana de Julia Correa. El Tutatis se llev\u00f3, adem\u00e1s, el premio a la mejor tripulaci\u00f3n femenina de la competici\u00f3n.<br \/>\nEl Campeonato de Espa\u00f1a de Sportboat de la Zona Norte qued\u00f3 finalmente desierto ya que ninguna tripulaci\u00f3n quiso optar al t\u00edtulo nacional que la Real Federaci\u00f3n Espa\u00f1ola de Vela puso en juego en el marco del Trofeo Repsol.<br \/>\nLa pr\u00f3xima cita con las regatas del Monte Real Club de Yates ser\u00e1 el 10 de junio con el Campeonato Gallego de A Dos, que volver\u00e1 a ser un a\u00f1o m\u00e1s Trofeo MRW e incluir\u00e1 el Memorial Rafael Olmedo, en homenaje al hist\u00f3rico presidente del club baion\u00e9s. Es el d\u00e9cimo segundo a\u00f1o consecutivo que el club baion\u00e9s organiza esta cita auton\u00f3mica por delegaci\u00f3n de la Real Federaci\u00f3n Gallega de Vela.<\/p>\n<p>TROFEO REPSOL 2023 \u2022 45\u00ba REGATA DE PRIMAVERA<br \/>\nClasificaci\u00f3n generalfinal tras la celebraci\u00f3n de 4 pruebas (2 costeras + 2 trapecios)<\/p>\n<p>CLASE ORC 1-2-3<\/p>\n<p>1. SAILWAY \u2022 RAM\u00d3N OJEA \u2022 CM CANIDO \u2022 2-2-2 \u2022 6 PUNTOS<br \/>\n2. BON III \u2022 V\u00cdCTOR CARRI\u00d3N \u2022 CN PUNTA LAGOA \u2022 1-8-1 \u2022 10 PUNTOS<br \/>\n3. NARVAL \u2022 JOS\u00c9 ANTONIO PORTAS \u2022 CN VILAGARC\u00cdA \u2022 3-4-3 \u2022 10 PUNTOS<\/p>\n<p>CLASE ORC 4<\/p>\n<p>1. DEEP BLUE 2.1 \u2022 VICENTE CID \u2022 RCN VIGO\u2022 1-1-1 \u2022 3 PUNTOS<br \/>\n2. UNUS \u2022 LUIS GARC\u00cdA TRIGO \u2022 MRCYB\u2022 3-2-2 \u2022 7 PUNTOS<br \/>\n3. LA BURLA NEGRA \u2022 JUAN JOS\u00c9 MART\u00cdNEZ \u2022 CN CASTRELO DE MI\u00d1O\u2022 2-3-3 \u2022 8 PUNTOS<\/p>\n<p>CLASE ORC 5<\/p>\n<p>1. CINCO ISLAS ALBARI\u00d1O \u2022 I\u00d1AKI CARBAJO \u2022 CN BELUSO \u2022 2-5-1 \u2022 8 PUNTOS<br \/>\n2. NAHELA \u2022 VICTOR MANUEL \u00c1LVAREZ \u2022 CD ALAGUA\u2022 1-3-4 \u2022 8 PUNTOS<br \/>\n2. SQUID II \u2022 FRANCISCO LUSQUI\u00d1OS \u2022 CN PORTONOVO \u2022 4-1,5-3 \u2022 8,5 PUNTOS<\/p>\n<p>CLASE A2<\/p>\n<p>1. SALA\u00d1O DOS \u2022 JACOBO VECINO Y BRENDA MAURE \u2022 RCN VIGO\u2022 1-1-1 \u2022 3 PUNTOS<br \/>\n2. AQUIL\u00d3N \u2022 ROBERTO TELLE Y GENOVEVA PEREIRO \u2022 MRCYB\u2022 2-2-2 \u2022 6 PUNTOS PUNTOS<br \/>\n3. ASANTE SANA \u2022 JUAN CARLOS TRABAZOS Y JOAQUIN DASILVA \u2022 LM BOUZAS\u2022 5-3-4\u2022 12 PUNTOS<\/p>\n<p>CLASE J80<\/p>\n<p>1. OKOFEN \u2022 JAVIER DE LA G\u00c1NDARA \u2022 MRCYB \u2022 3-1-1-2 \u2022 7 PUNTOS<br \/>\n2. MAR\u00cdAS \u2022 MANEL CUNHA \u2022 MRCYB \u2022 5-3-2-3 \u2022 13 PUNTOS<br \/>\n3. ALBOROTO \u2022 JAVIER AGUADO \u2022 MRCYB \u2022 2-2-9-1 \u2022 14 PUNTOS<\/p>\n<p>CLASE F\u00cdGARO<\/p>\n<p>1. TUTATIS \u2022 PAULA REY \u2022 MRCYB \u2022 6-5-7 \u2022 18 PUNTOS<br \/>\n2. LADEIRA \u2022 ELENA RAGA \u2022 MRCYB \u2022 8-6-5 \u2022 19 PUNTOS<br \/>\n3. ERIZANA \u2022 JULIA CORREA \u2022 MRCYB \u2022 5-9-8 \u2022 22 PUNTOS<\/p>\n<p>PREMIO ESPECIAL A LA MEJOR TRIPULACI\u00d3N FEMENINA DEL TROFEO<\/p>\n<p>TUTATIS \u2022 PAULA REY \u2022 MRCYB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trofeo Repsol El Parque Nacional de las Islas Atl\u00e1nticas de Galicia fue espectador de lujo este primero de mayo de la \u00faltima y decisiva jornada del Trofeo Repsol \u2022 45\u00ba Regata de Primavera, que vivi\u00f3 este lunes sus tres \u00faltimas pruebasen el fondeadero de las islas C\u00edes. Al igual que hab\u00eda sucedido en las dos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":47522,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[100],"tags":[3371],"class_list":["post-47521","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yachting","tag-trofeo-repsol"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/47521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/comments?post=47521"}],"version-history":[{"count":0,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/47521\/revisions"}],"wp:attachment":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/media?parent=47521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/categories?post=47521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/tags?post=47521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}