{"id":45906,"date":"2023-01-02T09:14:44","date_gmt":"2023-01-02T12:14:44","guid":{"rendered":"http:\/\/nautic.wnpower.host\/?p=45906"},"modified":"2023-01-02T09:14:44","modified_gmt":"2023-01-02T12:14:44","slug":"un-veterano-de-guerra-viajara-en-velero-al-cabo-de-hornos","status":"publish","type":"post","link":"https:\/\/nautica.news\/es\/un-veterano-de-guerra-viajara-en-velero-al-cabo-de-hornos\/","title":{"rendered":"Expedici\u00f3n de un Veterano de guerra al Cabo de Hornos"},"content":{"rendered":"<p><strong>Un veterano de guerra viajar\u00e1 en velero al Cabo de Hornos\u00a0<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-45912\" src=\"https:\/\/nautispots.com\/wp-content\/uploads\/2023\/01\/E47D5D30-1CAA-455C-AFA3-1FCF0F3949A2.png\" alt=\"\" width=\"1300\" height=\"983\" title=\"\" srcset=\"https:\/\/nautica.news\/es\/wp-content\/uploads\/sites\/2\/2023\/01\/E47D5D30-1CAA-455C-AFA3-1FCF0F3949A2.png 900w, https:\/\/nautica.news\/es\/wp-content\/uploads\/sites\/2\/2023\/01\/E47D5D30-1CAA-455C-AFA3-1FCF0F3949A2-300x227.png 300w, https:\/\/nautica.news\/es\/wp-content\/uploads\/sites\/2\/2023\/01\/E47D5D30-1CAA-455C-AFA3-1FCF0F3949A2-768x581.png 768w\" sizes=\"auto, (max-width: 1300px) 100vw, 1300px\" \/><\/p>\n<p><strong>Fuente: <a href=\"https:\/\/www.telam.com.ar\/notas\/202212\/615426-veterano-guerra-viajara-velero-cabo-hornos.html\" rel=\"noopener\">Telam<\/a><\/strong><\/p>\n<p><strong>El organizador de la expedici\u00f3n y sobreviviente del Crucero General Belgrano, Nilo Navas y su tripulaci\u00f3n, que la integran por primera vez dos mujeres, har\u00e1n la traves\u00eda a bordo del &#8220;Galileo&#8221; de la fundaci\u00f3n Malvinas Argentinas.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-45908\" src=\"https:\/\/nautispots.com\/wp-content\/uploads\/2023\/01\/081DFC9A-D07C-4502-977C-72750632310F.png\" alt=\"\" width=\"1004\" height=\"752\" title=\"\" srcset=\"https:\/\/nautica.news\/es\/wp-content\/uploads\/sites\/2\/2023\/01\/081DFC9A-D07C-4502-977C-72750632310F.png 900w, https:\/\/nautica.news\/es\/wp-content\/uploads\/sites\/2\/2023\/01\/081DFC9A-D07C-4502-977C-72750632310F-300x225.png 300w, https:\/\/nautica.news\/es\/wp-content\/uploads\/sites\/2\/2023\/01\/081DFC9A-D07C-4502-977C-72750632310F-768x575.png 768w\" sizes=\"auto, (max-width: 1004px) 100vw, 1004px\" \/><\/p>\n<p>Un velero en el que entre su tripulaci\u00f3n se encuentra un sobreviviente del hundimiento del crucero General Belgrano durante la guerra de Malvinas, zarpar\u00e1 en enero desde el puerto de Ushuaia con destino al cabo de Hornos, en el marco de una nueva traves\u00eda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-45911\" src=\"https:\/\/nautispots.com\/wp-content\/uploads\/2023\/01\/9AE07D29-ACC6-49C4-A657-6793DA56B2A9.png\" alt=\"\" width=\"1072\" height=\"597\" title=\"\" srcset=\"https:\/\/nautica.news\/es\/wp-content\/uploads\/sites\/2\/2023\/01\/9AE07D29-ACC6-49C4-A657-6793DA56B2A9.png 900w, https:\/\/nautica.news\/es\/wp-content\/uploads\/sites\/2\/2023\/01\/9AE07D29-ACC6-49C4-A657-6793DA56B2A9-300x167.png 300w, https:\/\/nautica.news\/es\/wp-content\/uploads\/sites\/2\/2023\/01\/9AE07D29-ACC6-49C4-A657-6793DA56B2A9-768x428.png 768w\" sizes=\"auto, (max-width: 1072px) 100vw, 1072px\" \/><\/p>\n<p>&#8220;Nosotros siempre, a\u00fan en la guerra, navegamos por aguas argentinas, esta vez en chilenas y vamos a Puerto Williams donde haremos migraciones, entre otros tr\u00e1mites&#8221;, agreg\u00f3 Navas, oriundo de Bah\u00eda Blanca.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-45910\" src=\"https:\/\/nautispots.com\/wp-content\/uploads\/2023\/01\/031E936A-206B-41C4-89E3-CCA034A38B5F.png\" alt=\"\" width=\"1004\" height=\"565\" title=\"\" srcset=\"https:\/\/nautica.news\/es\/wp-content\/uploads\/sites\/2\/2023\/01\/031E936A-206B-41C4-89E3-CCA034A38B5F.png 900w, https:\/\/nautica.news\/es\/wp-content\/uploads\/sites\/2\/2023\/01\/031E936A-206B-41C4-89E3-CCA034A38B5F-300x169.png 300w, https:\/\/nautica.news\/es\/wp-content\/uploads\/sites\/2\/2023\/01\/031E936A-206B-41C4-89E3-CCA034A38B5F-768x432.png 768w\" sizes=\"auto, (max-width: 1004px) 100vw, 1004px\" \/><\/p>\n<p>&#8220;Es por el tema de meteorolog\u00eda, hay que aguantar hasta que est\u00e9 adecuada y llegado el caso habr\u00e1 que estar en alguna caleta hasta que cambien mareas porque puede haber olas de hasta 30 metros&#8221;, indic\u00f3.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un veterano de guerra viajar\u00e1 en velero al Cabo de Hornos\u00a0 Fuente: Telam El organizador de la expedici\u00f3n y sobreviviente del Crucero General Belgrano, Nilo Navas y su tripulaci\u00f3n, que la integran por primera vez dos mujeres, har\u00e1n la traves\u00eda a bordo del &#8220;Galileo&#8221; de la fundaci\u00f3n Malvinas Argentinas. Un velero en el que entre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[86],"tags":[],"class_list":["post-45906","post","type-post","status-publish","format-standard","has-post-thumbnail","category-interes"],"jetpack_featured_media_url":"https:\/\/nautica.news\/es\/wp-content\/uploads\/sites\/2\/2023\/01\/42D48036-5E4E-4F18-98EF-9D845540C7CD.png","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/45906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/comments?post=45906"}],"version-history":[{"count":0,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/45906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/media\/45909"}],"wp:attachment":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/media?parent=45906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/categories?post=45906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/tags?post=45906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}