{"id":31689,"date":"2020-11-10T08:05:16","date_gmt":"2020-11-10T11:05:16","guid":{"rendered":"http:\/\/nautic.wnpower.host\/?p=31689"},"modified":"2020-11-10T08:05:16","modified_gmt":"2020-11-10T11:05:16","slug":"fiesta-y-descontrol-en-el-rio-parana","status":"publish","type":"post","link":"https:\/\/nautica.news\/es\/fiesta-y-descontrol-en-el-rio-parana\/","title":{"rendered":"Videos: Fiestas y Descontrol en el r\u00edo Paran\u00e1"},"content":{"rendered":"<p><strong>Fiestas \u00a0y Descontrol en el r\u00edo Paran\u00e1 <\/strong><\/p>\n<div style=\"position: relative;padding-bottom: 56.25%;height: 0;overflow: hidden\"> ?<\/div>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Rosario: fiesta y descontrol a orillas del r\u00edo Paran\u00e1\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/RhRkbfCkJnk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Mientras avanza la pandemia de coronavirus, y no cesan los contagios y tampoco los encuentros clandestinos masivos. Este fin de semana se viralizaron las im\u00e1genes de una \u00a0fiesta de espuma en el r\u00edo Paran\u00e1 frente Corrientes que se realiz\u00f3 en medio del r\u00edo y sin ning\u00fan tipo de control.<\/p>\n<p>Esta fiesta frente a la costa hab\u00eda ocurrido semanas atr\u00e1s y hab\u00edan participado unos 300 j\u00f3venes. La invitaci\u00f3n a la fiesta rezaba: \u201cmov\u00e9 tu lancha y junt\u00e9monos en el Banco de arena para vivir un poco el sol\u201d. Medios locales afirman que fue el s\u00e1bado pasado.<\/p>\n<p>Tambi\u00e9n este fin de semana hubo fiestas y descontrol el las playas de Rosario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fiestas \u00a0y Descontrol en el r\u00edo Paran\u00e1 ? &nbsp; Mientras avanza la pandemia de coronavirus, y no cesan los contagios y tampoco los encuentros clandestinos masivos. Este fin de semana se viralizaron las im\u00e1genes de una \u00a0fiesta de espuma en el r\u00edo Paran\u00e1 frente Corrientes que se realiz\u00f3 en medio del r\u00edo y sin ning\u00fan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31690,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[83],"tags":[190],"class_list":["post-31689","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-nautica","tag-rio-parana"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/31689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/comments?post=31689"}],"version-history":[{"count":0,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/31689\/revisions"}],"wp:attachment":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/media?parent=31689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/categories?post=31689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/tags?post=31689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}