{"id":3089,"date":"2017-01-11T21:04:03","date_gmt":"2017-01-12T00:04:03","guid":{"rendered":"http:\/\/nautic.wnpower.host\/?p=3089"},"modified":"2017-01-11T21:04:03","modified_gmt":"2017-01-12T00:04:03","slug":"52-super-series-en-key-west","status":"publish","type":"post","link":"https:\/\/nautica.news\/es\/52-super-series-en-key-west\/","title":{"rendered":"52 Super Series  en Key West"},"content":{"rendered":"<p>M\u00e1xima presi\u00f3n desde el primer d\u00eda de la Quantum Key West de 52 SUPER SERIES<\/p>\n<p>El nuevo Interlodge de Austin y Gwen Fragomen, recientemente botado, es la gran novedad en la Quantum Key West Race Week.<\/p>\n<p>La regata, la primera de la temporada 2017 de 52 SUPER SERIES, comienza el pr\u00f3ximo lunes en aguas de los cayos de Florida con once barcos TP52 en liza.<\/p>\n<p>Desde el primer momento se nota la presi\u00f3n en la flota. A\u00fan antes de haber comenzado la temporada. S\u00f3lo hace once semanas que la pasada campa\u00f1a termin\u00f3 con la victoria de Azzurra en aguas de Casc\u00e1is con la EGNOS 52 SUPER SERIES Casc\u00e1is Cup y ya estamos a las puertas de la siguiente. Once semanas en las que los once equipos que compiten en Florida han hecho cambios en los cascos, en los palos, las velas y, tambi\u00e9n, en las tripulaciones. Por eso los barcos ya van camino de Key West donde todos contemplan estos d\u00edas preliminares de entrenamiento como fundamentales para afrontar la temporada al m\u00e1ximo. Y es que en 52 SUPER SERIES vale tanto la primera como la \u00faltima manga y no se trata de llegar a la cita de Florida con dudas. De ah\u00ed toda la presi\u00f3n actual en la flota<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1xima presi\u00f3n desde el primer d\u00eda de la Quantum Key West de 52 SUPER SERIES El nuevo Interlodge de Austin y Gwen Fragomen, recientemente botado, es la gran novedad en la Quantum Key West Race Week. La regata, la primera de la temporada 2017 de 52 SUPER SERIES, comienza el pr\u00f3ximo lunes en aguas de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3090,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[100],"tags":[],"class_list":["post-3089","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yachting"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/3089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/comments?post=3089"}],"version-history":[{"count":0,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/3089\/revisions"}],"wp:attachment":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/media?parent=3089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/categories?post=3089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/tags?post=3089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}