{"id":2433,"date":"2016-11-21T14:57:57","date_gmt":"2016-11-21T17:57:57","guid":{"rendered":"http:\/\/nautic.wnpower.host\/?p=2433"},"modified":"2016-11-21T14:57:57","modified_gmt":"2016-11-21T17:57:57","slug":"como-se-forman-las-olas-de-mar","status":"publish","type":"post","link":"https:\/\/nautica.news\/es\/como-se-forman-las-olas-de-mar\/","title":{"rendered":"Como se forman las olas de mar"},"content":{"rendered":"<p><strong>Las<\/strong> <strong>olas marinas son formadas por la fricci\u00f3n que imprime el viento sobre la superficie mar\u00edtima,<\/strong> dichas olas son resultado de esta prolongaci\u00f3n entre ambos medios, el agua del mar y el aire de la atm\u00f3sfera.<\/p>\n<div id=\"bsa-html\" class=\"bsaProContainer bsaProContainer-6 bsa-html bsa-pro-col-1\"><\/div>\n<p>Las modificaciones en la <strong>presi\u00f3n atmosf\u00e9rica<\/strong>generan oscilaciones en la superficie del mar. A su vez, la acci\u00f3n del viento rozando esta superficie da lugar a lo que actualmente se conoce como ondas capilares (cuando el empuje es leve) y ondas gravitatorias (cuando esta fricci\u00f3n ejercida sobra la l\u00e1mina del agua tiene m\u00e1s intensidad.<\/p>\n<p>Por lo general, los vientos m\u00e1s intensos generan que las olas sean m\u00e1s altas. Aqu\u00ed entran en juego factores como la intensidad y la velocidad de la <strong>acci\u00f3n e\u00f3lica<\/strong>, tambi\u00e9n la cantidad de tiempo que el aire posee una direcci\u00f3n estable, la profundidad y la superficie afectada del agua. A medida que las olas van acerc\u00e1ndose a la orillas, estas avanzan m\u00e1s despacio, ya que la profundidad es menor, mientras que la altura de las cresta va aumentando.<\/p>\n<p><a class=\"td-modal-image\" href=\"http:\/\/www.grandesmedios.com\/wp-content\/uploads\/2016\/05\/Sabes-c%C3%B3mo-se-generan-las-olas-del-mar-1.png\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-29602\" src=\"http:\/\/www.grandesmedios.com\/wp-content\/uploads\/2016\/05\/Sabes-c%C3%B3mo-se-generan-las-olas-del-mar-1.png\" alt=\"Sabes c\u00f3mo se generan las olas del mar - 1\" width=\"974\" height=\"548\" title=\"\"><\/a>Este proceso contin\u00faa hasta que el sector elevado se mueve a mayor velocidad que la parte subacu\u00e1tica, punto en d\u00f3nde la ola rompe al ser desestabilizada por el movimiento.<\/p>\n<div id=\"bsa-html\" class=\"bsaProContainer bsaProContainer-8 bsa-html bsa-pro-col-1\"><\/div>\n<p>Adem\u00e1s, existen otra clase de olas de diferente origen, las cuales son las que constituyen el mar de fondo, m\u00e1s redondeadas y bajas. Estas surgen por las diferencias de salinidad, temperatura y presi\u00f3n entre las zonas aleda\u00f1as, las que generan el movimiento del agua d\u00f3nde estos par\u00e1metros son menores hac\u00eda \u00e1reas mayores. Al desplazarse el l\u00edquido forman las corrientes y por consecuencia las olas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las olas marinas son formadas por la fricci\u00f3n que imprime el viento sobre la superficie mar\u00edtima, dichas olas son resultado de esta prolongaci\u00f3n entre ambos medios, el agua del mar y el aire de la atm\u00f3sfera. Las modificaciones en la presi\u00f3n atmosf\u00e9ricageneran oscilaciones en la superficie del mar. A su vez, la acci\u00f3n del viento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2434,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[109],"tags":[],"class_list":{"0":"post-2433","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-medio-ambiente"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/2433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/comments?post=2433"}],"version-history":[{"count":0,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/2433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/media?parent=2433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/categories?post=2433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/tags?post=2433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}