{"id":21045,"date":"2019-09-16T19:52:15","date_gmt":"2019-09-16T22:52:15","guid":{"rendered":"http:\/\/nautic.wnpower.host\/?p=21045"},"modified":"2019-09-16T19:52:15","modified_gmt":"2019-09-16T22:52:15","slug":"new-york-yacht-club-2","status":"publish","type":"post","link":"https:\/\/nautica.news\/es\/new-york-yacht-club-2\/","title":{"rendered":"Comenz\u00f3 la Rolex New York Yacht Club Invitational Cup"},"content":{"rendered":"<h3>Rolex New York Yacht Club Invitational Cup<\/h3>\n<p>A\u00f1o diferente, barco diferente, pero el mismo rendimiento sobresaliente para San Diego Yacht Club.<\/p>\n<p>A trav\u00e9s de las cuatro carreras en la Rolex New York Yacht Club Invitational Cup de 2019, el primer campeonato de quilla de quilla de un solo dise\u00f1o de Corinto, el equipo de la Costa Oeste ha demostrado la incre\u00edble velocidad de la embarcaci\u00f3n, el trabajo en equipo de precisi\u00f3n y la perspicacia t\u00e1ctica que los calific\u00f3 para este prestigioso campeonato internacional hace un a\u00f1o.<\/p>\n<p>Con un primero, tercero y primero hoy, el patr\u00f3n de SDYC Tyler Sinks ha apostado a su tripulaci\u00f3n a una ventaja de 17 puntos despu\u00e9s de solo cuatro carreras.<\/p>\n<p>Queda mucho camino por recorrer en este evento, hasta ocho carreras m\u00e1s durante tres d\u00edas.<\/p>\n<p>La Rolex New York Yacht Club Invitational Cup es una regata bienal organizada por el New York Yacht Club Harbor Court en Newport, RI.<\/p>\n<p>Desde que el evento se realiz\u00f3 por primera vez en 2009, ha atra\u00eddo a los mejores navegantes aficionados de 43 de los clubes de yates m\u00e1s prestigiosos del mundo de 21 pa\u00edses<\/p>\n<p>Despu\u00e9s de cinco ediciones en la clase Swan 42, el evento 2019 se realizar\u00e1 en el IC37, dise\u00f1ado por Mark Mills y construido por Westerly Marine en Santa Ana, California, y FIBER Mechanics en el Reino Unido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rolex New York Yacht Club Invitational Cup A\u00f1o diferente, barco diferente, pero el mismo rendimiento sobresaliente para San Diego Yacht Club. A trav\u00e9s de las cuatro carreras en la Rolex New York Yacht Club Invitational Cup de 2019, el primer campeonato de quilla de quilla de un solo dise\u00f1o de Corinto, el equipo de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[83],"tags":[290],"class_list":["post-21045","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-nautica","tag-yacht-club"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/21045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/comments?post=21045"}],"version-history":[{"count":0,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/21045\/revisions"}],"wp:attachment":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/media?parent=21045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/categories?post=21045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/tags?post=21045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}