{"id":18498,"date":"2019-02-15T18:05:01","date_gmt":"2019-02-15T21:05:01","guid":{"rendered":"http:\/\/nautic.wnpower.host\/?p=18498"},"modified":"2019-02-15T18:05:01","modified_gmt":"2019-02-15T21:05:01","slug":"sailgp","status":"publish","type":"post","link":"https:\/\/nautica.news\/es\/sailgp\/","title":{"rendered":"Comenz\u00f3 el SailGP en Sydney"},"content":{"rendered":"<p>El primer evento de SailGP enciende a Sydney<\/p>\n<p>Jap\u00f3n toma el liderazgo temprano en la jornada inaugural de SailGP Sydney<\/p>\n<p>El puerto de Sydney proporcion\u00f3 un tel\u00f3n de fondo espectacular para el hist\u00f3rico lanzamiento mundial de SailGP.<\/p>\n<p>Frente a miles de espectadores, el equipo favorito de Jap\u00f3n, SailGP, aprovech\u00f3 el h\u00e1bil trabajo de la tripulaci\u00f3n y la experiencia previa de un gran catamar\u00e1n en el primer d\u00eda del estreno mundial de SailGP.<\/p>\n<p>El equipo japon\u00e9s, dirigido por Nathan Outteridge, obtuvo una gran victoria en la primera carrera. Lo siguieron con dos finales en segundo lugar, una actuaci\u00f3n que los lleva a liderar a los favoritos de la ciudad en un punto a mitad del evento de apertura del campeonato.<\/p>\n<p>Con la adrenalina recorriendo las venas y las cabezas fr\u00edas, el equipo australiano de Slingsby se recuper\u00f3 para obtener dos victorias de regreso, en las carreras dos y tres. Su sorpresa cuarta en la carrera inaugural detuvo al equipo local detr\u00e1s del l\u00edder global Jap\u00f3n cuando se contaron los puntos del d\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El primer evento de SailGP enciende a Sydney Jap\u00f3n toma el liderazgo temprano en la jornada inaugural de SailGP Sydney El puerto de Sydney proporcion\u00f3 un tel\u00f3n de fondo espectacular para el hist\u00f3rico lanzamiento mundial de SailGP. Frente a miles de espectadores, el equipo favorito de Jap\u00f3n, SailGP, aprovech\u00f3 el h\u00e1bil trabajo de la tripulaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18500,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[85],"tags":[526],"class_list":["post-18498","post","type-post","status-publish","format-standard","has-post-thumbnail","category-vela-noticias-torneos-copas","tag-sailgp"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/18498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/comments?post=18498"}],"version-history":[{"count":0,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/18498\/revisions"}],"wp:attachment":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/media?parent=18498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/categories?post=18498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/tags?post=18498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}