{"id":14291,"date":"2018-05-04T19:13:36","date_gmt":"2018-05-04T22:13:36","guid":{"rendered":"http:\/\/nautic.wnpower.host\/?p=14291"},"modified":"2018-05-04T19:13:36","modified_gmt":"2018-05-04T22:13:36","slug":"sail-racing-palmavela-estrena","status":"publish","type":"post","link":"https:\/\/nautica.news\/es\/sail-racing-palmavela-estrena\/","title":{"rendered":"Sail Racing PalmaVela estrena"},"content":{"rendered":"<p><strong>Sail Racing PalmaVela estrena<\/strong><\/p>\n<p>La primera jornada de competici\u00f3n de la 15\u00aa Sail Racing PalmaVela ha permitido subir parciales a los casilleros de las siete clases convocadas hoy para competir en la bah\u00eda de Palma. Equipos de seis nacionalidades encabezan la provisional a la espera de que ma\u00f1ana se incorporen otras seis clases y la flota supere los 120 barcos.<\/p>\n<p>Hoy han competido siete de las 14 clases participantes en la 15\u00aa Sail Racing PalmaVela, con un programa compuesto por pruebas costeras para los Wally y los IRC, y mangas barlovento-sotavento para los TP52, ClubSwan 50, Swan 45, ClubSwan 42 y Melges 40. El viento tard\u00f3 en establecerse en la zona donde se instalaron los campos de las clases que compet\u00edan entre bastones, retrasando la primera salida del d\u00eda cerca de una hora. Para cuando se estableci\u00f3 la brisa, sopl\u00f3 de componente suroeste con intensidades en el entorno de los 12 nudos, permitiendo el cumplimiento del programa previsto. En el centro de la bah\u00eda, Wally e IRC sal\u00edan casi en hora para completar un recorrido de 32 millas hasta Illetas, Santa Ponsa y vuelta al centro de la bah\u00eda.<\/p>\n<p>La clasificaci\u00f3n provisional al t\u00e9rmino de esta primera jornada est\u00e1 encabezada por equipos de seis nacionalidades diferentes, reflejo del car\u00e1cter internacional de la flota de la 15\u00aa Sail Racing PalmaVela. Lideran el brit\u00e1nico J-One (clase Wally), el espa\u00f1ol Pelotari Project (IRC), el italoargentino Azzurra (TP52), los alemanes Earlybird (ClubSwan 50) y Elena Nova (Swan 45), el holand\u00e9s Selene Alifax (ClubSwan 42) y el sueco Inga from Sweden (Melges 40).<\/p>\n<p>Wally: Costera para J-One<br \/>\nLa flota compuesta por barcos de mayor eslora navegaba hoy en formato costero. Los espectaculares WallyCento Galateia y Tango protagonizaron un intenso duelo que termin\u00f3 con llegada de foto finish, parando el crono literalmente en el mismo segundo. Pero la compensaci\u00f3n de tiempos favoreci\u00f3 al m\u00e1s peque\u00f1o de la flota, el Wally 77 brit\u00e1nico J-One de Piers Richardson, que complet\u00f3 el recorrido casi 45 minutos m\u00e1s tarde que los dos colosos, suficiente para convertirse en primer l\u00edder de la semana.<\/p>\n<p>IRC: Victoria para el espa\u00f1ol Pelotari Project<br \/>\nLa heterog\u00e9nea flota IRC tambi\u00e9n se enfrent\u00f3 en un recorrido de casi 32 millas por la bah\u00eda de Palma. El primero en cruzar la meta ser\u00eda el 80 pies brit\u00e1nico Aegir, que invirti\u00f3 poco m\u00e1s de cuatro horas, pero la victoria en compensado corresponder\u00eda al X-65 espa\u00f1ol Pelotari Project de Andr\u00e9s Varela Entrecanales, que encabeza la provisional de cara a la segunda jornada.<\/p>\n<p>TP52: A Azzurra le gusta Palma<br \/>\nEl regreso de la flota TP52 a la Sail Racing PalmaVela ha respondido a las altas expectativas generadas por el estreno de siete barcos in\u00e9ditos que coincid\u00edan por primera vez en un campo de regatas. El italoargentino Azzurra de Guillermo Parada y el t\u00e1ctico Santiago Lange, campe\u00f3n de las 52 SuperSeries y vencedor en la PalmaVela de 2016 (la \u00faltima con participaci\u00f3n de la clase), emerge como primer l\u00edder de la categor\u00eda despu\u00e9s de ganar la primera manga del d\u00eda y firmar un tres en la segunda, ganada por el alem\u00e1n Platoon.<\/p>\n<p>ClubSwan 50: Jornada casi perfecta para Earlybird<br \/>\nLa lucha tambi\u00e9n ha sido intensa hoy entre los monotipos ClubSwan 50. El mejor de la jornada ha sido el alem\u00e1n Earlybird del t\u00e1ndem formado por el armador Hendrik Brandis y el t\u00e1ctico Jochen Sch\u00fcmann. El actual campe\u00f3n de Europa de la categor\u00eda y ganador de la Copa del Rey MAPFRE 2017 firm\u00f3 una tarjeta casi perfecta (1-2-1) y s\u00f3lo cedi\u00f3 el triunfo parcial en la segunda del d\u00eda ante el ruso Skorpios de Andrey Konogorov. Debutaba el espa\u00f1ol A5 de Jaime Rodr\u00edguez Toubes, que volvi\u00f3 a tierra con unos parciales de 6-7-7.<\/p>\n<p>Swan 45: Elena Nova busca defender t\u00edtulo<br \/>\nEn clase Swan 45, arranca la semana en cabeza de la provisional el defensor del t\u00edtulo. El alem\u00e1n Elena Nova de Christian Plump se impuso en las dos primeras mangas y fue tercero en la \u00faltima del d\u00eda, ganada por el espa\u00f1ol Porr\u00f3n IX de Lu\u00eds Sen\u00eds, actual campe\u00f3n del mundo de Swan 45, que es tercero provisional por detr\u00e1s del holand\u00e9s K-Force.<\/p>\n<p>ClubSwan 42: Selene Alifax, impecable<br \/>\nLa mejor tarjeta de la jornada se firm\u00f3 en clase ClubSwan 42. El holand\u00e9s Selene Alifax de Massimo de Campo no dio opci\u00f3n a sus rivales, ganando las tres mangas para regresar al RCNP como l\u00edder indiscutible y cuatro puntos de ventaja sobre su inmediato perseguidor, el Pez de Abril de Jos\u00e9 Mar\u00eda Meseguer. El barco espa\u00f1ol, actual subcampe\u00f3n de Europa de la categor\u00eda, fue el segundo mejor del d\u00eda merced a unos parciales de 2-2-3.<\/p>\n<p>Melges 40: Inga from Sweden, primer l\u00edder<br \/>\nLos tres primeros asaltos de Melges 40 en su debut en la Sail Racing PalmaVela sirvieron para demostrar el atractivo de este monotipo estadounidense, confirmado tambi\u00e9n para la Copa del Rey MAPFRE. Tres barcos se repartieron las tres victorias parciales en juego, pero el m\u00e1s regular de la jornada fue el sueco Inga from Sweden patroneado por Richard Goransson, que se convierte en primer l\u00edder provisional de la clase tras anotar 1-2-4.<\/p>\n<p>Ma\u00f1ana se incorporan otras seis clases<br \/>\nLa segunda jornada del programa de competici\u00f3n de la Sail Racing PalmaVela citar\u00e1 a las clases que han debutado hoy y a\u00f1adir\u00e1 a otros 80 barcos de categor\u00edas ORC, J80, Drag\u00f3n, Flying Fifteen, Cl\u00e1sicos y Esp\u00edritu de Tradici\u00f3n, ampliando hasta cerca de 130 el n\u00famero de barcos en el agua. S\u00f3lo quedar\u00e1n en tierra los nueve participantes de clase Hansa 303, que competir\u00e1n a partir del s\u00e1bado.<\/p>\n<p>La 15\u00aa Sail Racing PalmaVela es puntuable para el circuito oficial de clase Wally y para la Nations Trophy Mediterranean League de monotipos Swan. Est\u00e1 organizada por el Real Club N\u00e1utico de Palma y la Real Federaci\u00f3n Espa\u00f1ola de Vela, con el patrocinio de Sail Racing, el patrocinio institucional del Govern de les Illes Balears y el Ajuntament de Palma, y con la colaboraci\u00f3n de la Federaci\u00f3n Balear de Vela, Club N\u00e1utic S\u2019Arenal y la Autoridad Portuaria de Baleares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sail Racing PalmaVela estrena La primera jornada de competici\u00f3n de la 15\u00aa Sail Racing PalmaVela ha permitido subir parciales a los casilleros de las siete clases convocadas hoy para competir en la bah\u00eda de Palma. Equipos de seis nacionalidades encabezan la provisional a la espera de que ma\u00f1ana se incorporen otras seis clases y la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14292,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[100],"tags":[],"class_list":["post-14291","post","type-post","status-publish","format-standard","has-post-thumbnail","category-yachting"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/14291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/comments?post=14291"}],"version-history":[{"count":0,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/14291\/revisions"}],"wp:attachment":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/media?parent=14291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/categories?post=14291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/tags?post=14291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}