{"id":11279,"date":"2017-12-14T08:38:36","date_gmt":"2017-12-14T11:38:36","guid":{"rendered":"http:\/\/nautic.wnpower.host\/?p=11279"},"modified":"2017-12-14T08:38:36","modified_gmt":"2017-12-14T11:38:36","slug":"barcelona-world-race-nueva-etapa","status":"publish","type":"post","link":"https:\/\/nautica.news\/es\/barcelona-world-race-nueva-etapa\/","title":{"rendered":"Barcelona World Race , nueva etapa"},"content":{"rendered":"<p>La Barcelona World Race ha presentado a la comunidad n\u00e1utica su nuevo formato que abre nuevos horizontes de expansi\u00f3n a la flota IMOCA.<\/p>\n<p> Considerada una de las m\u00e1s importantes regatas de vuelta al mundo, introduce en su cuarta edici\u00f3n emocionantes ingredientes: dos etapas, Barcelona-S\u00eddney-Barcelona, y la posibilidad de cambiar de copatr\u00f3n. La vuelta al mundo a dos ha suscitado el entusiasmo de regatistas de todo el mundo: 16 equipos han incluido la regata en su calendario de competici\u00f3n.<\/p>\n<p>La Barcelona World Race ha presentado a la comunidad n\u00e1utica su nuevo formato que abre nuevos horizontes de expansi\u00f3n a la flota IMOCA. Considerada una de las m\u00e1s importantes regatas de vuelta al mundo, introduce en su cuarta edici\u00f3n emocionantes ingredientes: dos etapas, Barcelona-S\u00eddney-Barcelona, y la posibilidad de cambiar de copatr\u00f3n. La vuelta al mundo a dos ha suscitado el entusiasmo de regatistas de todo el mundo: 16 equipos han incluido la regata en su calendario de competici\u00f3n.<\/p>\n<p>La cuenta atr\u00e1s para la Barcelona World Race 2018\/19 ha comenzado hoy con una presentaci\u00f3n a la comunidad n\u00e1utica internacional en la sede de la Fundaci\u00f3 Navegaci\u00f3 Oce\u00e0nica Barcelona (FNOB). La cuarta edici\u00f3n de la vuelta al mundo a dos (dos tripulantes por barco) llega con importantes novedades que la sit\u00faan como una de las dos pruebas m\u00e1s destacadas del calendario del Campeonato del Mundo IMOCA, junto a la Vende\u00e9 Glob\u00e9.<br \/>\nEl 12 de enero de 2019 dar\u00e1 inicio la nueva edici\u00f3n de la regata de vuelta al mundo a vela a dos en la que, por primera vez, los barcos IMOCA 60 har\u00e1n una parada obligatoria en S\u00eddney, lo que significa un importante impulso a la regata y a la clase a nivel internacional. Por otro lado, en la pr\u00f3xima edici\u00f3n, la FNOB contar\u00e1 con una nueva sede y centro de control en la ciudad de Barcelona, dedicado al seguimiento de la regata. Estar\u00e1 situado en el espacio Sea Experience, junto al centro comercial Maremagnum, lo que acercar\u00e1 todav\u00eda m\u00e1s la competici\u00f3n a los ciudadanos, que podr\u00e1n visitar las instalaciones.<br \/>\nLa pr\u00f3xima edici\u00f3n de la regata ha despertado ya un gran inter\u00e9s entre los navegantes de gran talla tanto nacional como internacional, y 16 equipos ya la han incluido en su calendario de competici\u00f3n, 11 de los cuales cuentan con un IMOCA 60. La regata ha suscitado el inter\u00e9s de 26 navegantes internacionales que han pedido informaci\u00f3n a la Direcci\u00f3n de Regata.<br \/>\n\u201cPara nosotros ser\u00eda un \u00e9xito tener entre 10 y 11 barcos en la l\u00ednea de salida en la pr\u00f3xima edici\u00f3n de la regata\u201d, ha se\u00f1alado Xos\u00e9-Carlos Fern\u00e1ndez, director general de la FNOB. Fern\u00e1ndez ha abierto la presentaci\u00f3n de hoy destacando el significado de la Barcelona World Race para el deporte de la vela oce\u00e1nica internacional y muy en especial para la ciudad de Barcelona, donde la regata se ha afianzado en el patrimonio de los barceloneses y que ahora se proyecta a\u00fan m\u00e1s con la uni\u00f3n con S\u00eddney. \u201cHasta ahora no hab\u00eda ning\u00fan punto donde pudi\u00e9semos dar visibilidad extra a los sponsors, por eso ahora hacemos parada en S\u00eddney. Esta ciudad de referencia hace que la regata sea muy atractiva para el patrocinio\u201d.<br \/>\nEl director general de la FNOB ha hecho especial hincapi\u00e9 en que la Barcelona World Race aglutina y expande la filosof\u00eda de los ejes de trabajo de la Fundaci\u00f3n &#8211; deporte, formaci\u00f3n, ciencia y empresa -, con los que la vela oce\u00e1nica demuestra su enorme potencial para beneficiar al tejido social que la rodea.<br \/>\nPor su parte, Jacques Cara\u00ebs, director de regata de la Barcelona World Race, ha explicado el nuevo formato de la vuelta al mundo que tendr\u00e1 su salida el 12 de enero de 2019 y que constar\u00e1 de dos etapas. La primera, Barcelona &#8211; S\u00eddney, de 13.500 millas n\u00e1uticas, con llegada prevista a la ciudad australiana a finales de febrero; y la segunda, de 12.500 millas n\u00e1uticas, con salida de S\u00eddney el 9 de marzo y llegada a Barcelona a mediados de abril. Cara\u00ebs ha explicado el funcionamiento del opcional cambio de copatr\u00f3n en la segunda etapa y los pormenores de la calificaci\u00f3n para regata. Tambi\u00e9n ha se\u00f1alado la importancia de la Barcelona World Race en el calendario de la clase: \u201cLa Barcelona World Race tendr\u00e1 un coeficiente 9 para las Globe Series, el Campeonato del Mundo IMOCA yuna etapa calificar\u00e1 para la Vend\u00e9e Globe 2020. Hemos trabajado para que los equipos tengan las m\u00e1ximas posibilidades de terminar la regata: los equipos podr\u00e1n hacer una parada t\u00e9cnica por etapa, con una duraci\u00f3n m\u00e1xima de 48 horas cada una\u201d.<br \/>\nPor su parte Julia Casanueva, presidenta de la Real Federaci\u00f3n Espa\u00f1ola de Vela (RFEV), ha destacado la importancia de la regata en Espa\u00f1a y ha manifestado su apoyo a la organizaci\u00f3n de la cuarta edici\u00f3n: \u201cLa Barcelona World Race proporciona una excelente oportunidad a nuestros regatistas oce\u00e1nicos de incorporarse al circuito internacional de vela oce\u00e1nica. Sin duda es una plataforma \u00fanica no s\u00f3lo para nuestros para nuestros deportistas, sino tambi\u00e9n para los armadores, jefes de equipo y dem\u00e1s profesionales de la vela que tienen una oportunidad de crecimiento profesional en este evento\u201d.<br \/>\nJulia Casanueva ha corroborado y apoyado el papel de la FNOB en la creaci\u00f3n de un nuevo modelo que acerca la sociedad al deporte de la vela de una forma altamente beneficiosa para ambos: \u201cLa Barcelona World Race, a trav\u00e9s de sus programas educativos e industriales, facilita la aproximaci\u00f3n de nuevos patrocinadores a nuestro deporte. Este modelo de organizaci\u00f3n propuesto desde hace a\u00f1os por la Fundaci\u00f3n ha hecho que la vela oce\u00e1nica, sin dejar de ser un deporte de alto nivel t\u00e9cnico, aporte tambi\u00e9n una gran utilidad social en el \u00e1mbito de la formaci\u00f3n y de la actividad empresarial\u201d.<br \/>\nXavier Torres, presidente de la Federaci\u00f3n Catalana de Vela, ha destacado: \u201cEstamos al lado de la FNOB y de la regata, para nosotros la Barcelona World Race da acceso a la vela oce\u00e1nica a los regatistas catalanes. Es una gran oportunidad para ellos. El formato es m\u00e1s atractivo y es normal que tantos equipos muestren inter\u00e9s. Tambi\u00e9n estamos orgullosos de que Barcelona se proyecte en el mundo de la vela\u201d.<br \/>\nAntoine Mermod, presidente de la IMOCA, ha destacado en su intervenci\u00f3n la magn\u00edfica evoluci\u00f3n de la Barcelona World Race desde su primera edici\u00f3n y c\u00f3mo la regata se ha ganado un puesto clave en el calendario del Campeonato del Mundo de la clase: \u201cDisponemos de dos regatas estrella: la Vend\u00e9e Globe, en solitario, y la Barcelona World Race, a dos; es decir una vuelta al mundo cada dos a\u00f1os, una f\u00f3rmula que ha funcionado muy bien ya que es apreciada por los regatistas y sus patrocinadores; y que ahora, con el nuevo formato de la Barcelona World Race en dos etapas se va a afianzar. El trabajo de la FNOB a lo largo de estos 10 a\u00f1os ha sido extraordinario y no cabe duda que la cuarta edici\u00f3n de la Barcelona World Race ser\u00e1 a\u00fan m\u00e1s exitosa\u201d.<br \/>\nMarcus Hutchinson, reconocido internacionalmente en el \u00e1mbito la organizaci\u00f3n y direcci\u00f3n de equipos de competici\u00f3n, ha destacado la importancia de la Barcelona World Race para el desarrollo de la carrera deportiva de los regatistas y para generar oportunidades de patrocinio. \u201cEste cambio de formato, con dos etapas, es un avance important\u00edsimo para la internacionalizaci\u00f3n de la clase IMOCA\u201d.<br \/>\nEl navegante barcelon\u00e9s Didac Costa ha cerrado el acto manifestando su inter\u00e9s en participar en la pr\u00f3xima edici\u00f3n, que ser\u00eda su tercera vuelta al mundo tras la Barcelona World Race 2014\/15 y la Vend\u00e9e Globe 2016: \u201cEstoy totalmente a favor de este nuevo formato. Para m\u00ed, siendo de Barcelona, esta regata es muy especial y significa mucho en mi carrera\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Barcelona World Race ha presentado a la comunidad n\u00e1utica su nuevo formato que abre nuevos horizontes de expansi\u00f3n a la flota IMOCA. Considerada una de las m\u00e1s importantes regatas de vuelta al mundo, introduce en su cuarta edici\u00f3n emocionantes ingredientes: dos etapas, Barcelona-S\u00eddney-Barcelona, y la posibilidad de cambiar de copatr\u00f3n. La vuelta al mundo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[168],"tags":[],"class_list":["post-11279","post","type-post","status-publish","format-standard","has-post-thumbnail","category-barcelona-world-race"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/11279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/comments?post=11279"}],"version-history":[{"count":0,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/posts\/11279\/revisions"}],"wp:attachment":[{"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/media?parent=11279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/categories?post=11279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nautica.news\/es\/wp-json\/wp\/v2\/tags?post=11279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}